{"id":704,"date":"2020-03-30T16:35:31","date_gmt":"2020-03-30T07:35:31","guid":{"rendered":"https:\/\/senseki.com\/blog\/?p=704"},"modified":"2020-04-01T10:45:39","modified_gmt":"2020-04-01T01:45:39","slug":"%e5%a4%96%e6%9d%a5%e6%8b%85%e5%bd%93%e5%8c%bb%e8%a1%a8%e5%a4%89%e6%9b%b4%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b%ef%bc%882020%e5%b9%b44%e6%9c%88%e3%82%88%e3%82%8a%ef%bc%89","status":"publish","type":"post","link":"https:\/\/senseki.com\/blog\/info\/704\/","title":{"rendered":"\u5916\u6765\u62c5\u5f53\u533b\u8868\u5909\u66f4\u306e\u304a\u77e5\u3089\u305b\uff082020\u5e744\u6708\u3088\u308a\uff09"},"content":{"rendered":"<p>2020\u5e744\u6708\u3088\u308a\u5916\u6765\u62c5\u5f53\u533b\u8868\u304c\u5909\u66f4\u306b\u306a\u308a\u307e\u3059\u3002<\/p>\n<p>\u8a73\u3057\u3044\u5185\u5bb9\u306f<a href=\"https:\/\/senseki.com\/pdf\/schedule202004.pdf\">4\u6708\u5916\u6765\u62c5\u5f53\u533b\u8868\uff08pdf\uff09<\/a>\u3067\u3054\u78ba\u8a8d\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2020\u5e744\u6708\u3088\u308a\u5916\u6765\u62c5\u5f53\u533b\u8868\u304c\u5909\u66f4\u306b\u306a\u308a\u307e\u3059\u3002 \u8a73\u3057\u3044\u5185\u5bb9\u306f4\u6708\u5916\u6765\u62c5\u5f53\u533b\u8868\uff08pdf\uff09\u3067\u3054\u78ba\u8a8d\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-704","post","type-post","status-publish","format-standard","hentry","category-info"],"_links":{"self":[{"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/posts\/704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/comments?post=704"}],"version-history":[{"count":2,"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/posts\/704\/revisions"}],"predecessor-version":[{"id":706,"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/posts\/704\/revisions\/706"}],"wp:attachment":[{"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/media?parent=704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/categories?post=704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senseki.com\/blog\/wp-json\/wp\/v2\/tags?post=704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}